{"id":14380,"date":"2017-03-03T00:00:00","date_gmt":"2017-03-03T00:00:00","guid":{"rendered":"https:\/\/www.isdi.education\/es\/el-coding-para-los-mas-pequenos\/"},"modified":"2024-04-22T14:46:22","modified_gmt":"2024-04-22T14:46:22","slug":"el-coding-para-los-mas-pequenos","status":"publish","type":"post","link":"https:\/\/www.isdi.education\/es\/blog\/el-coding-para-los-mas-pequenos","title":{"rendered":"CODING EDUCATIVO"},"content":{"rendered":"<div id=\"07M-wysiwyg-1\" class=\"07M-wysiwyg anchor--link \" data-anchor-content>\n<section class=\"wysiwyg mb-xl\">\n<div class=\"wrapper wrapper--small\">\n<p class=\"t-small mb-xs\">\n<div class=\"wysiwyg__content\">\n<div>\n<p class=\"rtejustify\" dir=\"ltr\">No dejamos de hablar de los empleos m\u00e1s demandados y de las profesiones del futuro, sin embargo muchas veces dejamos pasar de largo lo m\u00e1s importante, la formaci\u00f3n en el mundo digital para los m\u00e1s peque\u00f1os.\u00a0Las nuevas generaciones entran en este nuevo universo desde que tienen uso de sus manitas y empiezan a pasar las pantallas de los smartphones de sus padres.\u00a0Muchas colegios empiezan a implementar parte de \u00e1rea formativa a la formaci\u00f3n en habilidades tecnol\u00f3gicas. La programaci\u00f3n o coding es una de las tendencias educativas que comienza a instaurarse dentro de los centros formativos para los m\u00e1s peque\u00f1os.<\/p>\n<p class=\"rtejustify\" dir=\"ltr\">Seg\u00fan los expertos \u201cla ense\u00f1anza de la programaci\u00f3n a estudiantes desarrolla el pensamiento l\u00f3gico-sistem\u00e1tico, prepara al alumno para obtener un mayor nivel profesional y de competencia laboral\u201d.\u00a0El coding en colegios pretende ense\u00f1ar lenguajes de programaci\u00f3n desde una edad temprana para que empiecen a familiarizarse y desenvolverse con los conceptos m\u00e1s b\u00e1sicos, como v\u00eda para desarrollar futuras habilidades digitales.<\/p>\n<p class=\"rtejustify\" dir=\"ltr\">En la actualidad para los adultos supone una inversi\u00f3n en tiempo y educaci\u00f3n aprender la utilizaci\u00f3n de los lenguajes de coding y programaci\u00f3n, en el futuro acabar\u00e1 siendo un idioma m\u00e1s, tan natural para las personas como hablar tu propia lengua.\u00a0<\/p>\n<p class=\"rtejustify\" dir=\"ltr\">Es por esto que cada vez m\u00e1s ni\u00f1os destinan desde sus escuelas, parte de su tiempo de estudio a fomentar este conocimiento.<\/p>\n<p class=\"rtejustify\" dir=\"ltr\">\u00a0<\/p>\n<p class=\"rtejustify\" dir=\"ltr\"><u><strong>APRENDER A PROGRAMAR JUGANDO<\/strong><\/u><\/p>\n<p class=\"rtejustify\" dir=\"ltr\">Siguiendo en la l\u00ednea de la ense\u00f1anza y el aprendizaje, debemos tener en cuenta que nuestra sociedad los smartphones juegan un papel muy importante en nuestro d\u00eda d\u00eda y son una herramienta muy \u00fatil para que los m\u00e1s peque\u00f1os comiencen su aventura en universo del coding.<\/p>\n<p class=\"rtejustify\" dir=\"ltr\">Este tipo de iniciativas ya se llevaban a cabo a trav\u00e9s de los ordenadores, y aunque nunca hay que dejar de lado esta pr\u00e1ctica, siendo realistas los ordenadores (aun los port\u00e1tiles) no solo limitan su uso a un espacio y tiempo espec\u00edfico sino que adem\u00e1s las nuevas generaciones se sienten m\u00e1s c\u00f3modos y familiarizados con el entorno m\u00f3vil.<\/p>\n<p class=\"rtejustify\" dir=\"ltr\">\u00a0<\/p>\n<p class=\"rtejustify\" dir=\"ltr\"><u><strong>APPS DE APRENDIZAJE DE CODING PARA NI\u00d1OS<\/strong><\/u>\u00a0<\/p>\n<p class=\"rtejustify\" dir=\"ltr\"><strong>&#8211; ScratchJr<\/strong><\/p>\n<p class=\"rtejustify\" dir=\"ltr\">Es un juego puzzle basado en Scratch, un lenguaje de programaci\u00f3n destinado a introducir a los m\u00e1s peque\u00f1os (a partir de 5 a\u00f1os) en el mundo de la programaci\u00f3n.<\/p>\n<p class=\"rtejustify\" dir=\"ltr\">El juego les permite dise\u00f1ar sus propios juegos e historias escogiendo y editando escenarios y personajes y a\u00f1adiendo una serie de \u00f3rdenes l\u00f3gicas en forma de acciones (andar, saltar, agarrar\u2026) Se trata de bloques que el ni\u00f1o debe colocar. Todos estos bloques o piezas est\u00e1n explicados, y la animaci\u00f3n se realiza arrastrando y soltando las piezas. Las posibilidades de creaci\u00f3n de scripts son casi infinitas. \u00a0<\/p>\n<p class=\"rtejustify\" dir=\"ltr\">Est\u00e1 dise\u00f1ado como una introducci\u00f3n incluso anterior a la programaci\u00f3n inform\u00e1tica y la creaci\u00f3n multimedia. Aunque ScratchJr est\u00e1 dise\u00f1ado para ni\u00f1os peque\u00f1os, se requiere ayuda de un adulto para que los ni\u00f1os pueda sacarle todo el partido. Tiene instrucciones en pantalla y una gu\u00eda de animaci\u00f3n.<\/p>\n<p class=\"rtejustify\" dir=\"ltr\">Tiene versi\u00f3n web y funciona tanto para Android como para iPhone.<\/p>\n<p class=\"rtejustify\" dir=\"ltr\"><strong>&#8211; Tynker<\/strong><\/p>\n<p class=\"rtejustify\" dir=\"ltr\">La interfaz es similar a Scratch. Pero mientras que Scratch se dise\u00f1\u00f3 para programar, Tynker tiene como base ense\u00f1ar a los peque\u00f1os c\u00f3mo programar, es decir, la aplicaci\u00f3n cuenta con cursos de iniciaci\u00f3n, herramientas de gesti\u00f3n de aulas, y una galer\u00eda online de los programas creados por los estudiantes. De esta manera podr\u00e1n seguir las clases a su ritmo de forma sencilla y sin necesidad de la ayuda de los padres.<\/p>\n<p class=\"rtejustify\" dir=\"ltr\">La aplicaci\u00f3n pone especial \u00e9nfasis en la parte visual-creativa del proceso de desarrollo de juegos, permitiendo a los peque\u00f1os escoger plantillas de todo tipo: escenarios, personajes, m\u00fasica\u2026 Cada uno de estos elementos pueden personalizarse y, tambi\u00e9n puede hacerse interactivo a trav\u00e9s de la introducci\u00f3n de comandos l\u00f3gicos en formato bloque de lego.<\/p>\n<p class=\"rtejustify\" dir=\"ltr\">Funciona tanto para Android como para iPhone.<\/p>\n<p class=\"rtejustify\" dir=\"ltr\"><strong>&#8211; Hopscotch<\/strong><\/p>\n<p class=\"rtejustify\" dir=\"ltr\">Hopscotch ense\u00f1a a los ni\u00f1os a programar a trav\u00e9s del uso de bloques de construcci\u00f3n simples e intuitivos. Con esta app podr\u00e1n crear crear juegos, animaciones y otros programas en un entorno altamente visual e interactivo. Pueden programar personajes para que se muevan, dibujen y entren en contacto los unos con los otros. Los ni\u00f1os pueden usar el ipad como control ya sea sacudi\u00e9ndolo, inclin\u00e1ndolo o incluso gritando, lo cual incentiva tambi\u00e9n su creatividad y les estimula en un ambiente de juego y diversi\u00f3n. Hopscotch se inspir\u00f3 en el editor multimedia Scratch y le proporciona a los ni\u00f1os una forma creativa para aprender los fundamentos de la programaci\u00f3n inform\u00e1tica.<\/p>\n<p class=\"rtejustify\" dir=\"ltr\"><strong>&#8211; Daisy the Dinosaur<\/strong><\/p>\n<p class=\"rtejustify\" dir=\"ltr\">Los ni\u00f1os aprenden los conceptos b\u00e1sicos de la programaci\u00f3n inform\u00e1tica a trav\u00e9s del personaje principal Daisy. Es una app gratuita muy divertida para ni\u00f1os de todas las edades.\u00a0Gracias a su sencilla interfaz los peque\u00f1os podr\u00e1n comprender intuitivamente algunos fundamentos b\u00e1sicos de la programaci\u00f3n: objetos, secuenciaci\u00f3n, bucles y eventos mediante la resoluci\u00f3n de retos.\u00a0Otro de los elementos a destacar de la aplicaci\u00f3n es que, una vez que los ni\u00f1os la hayan utilizado podr\u00e1n optar por descargar un kit para programar su propio juego de ordenador.<\/p>\n<p class=\"rtejustify\" dir=\"ltr\"><strong>&#8211; Move the Turtle<\/strong><\/p>\n<p class=\"rtejustify\" dir=\"ltr\">App enfocada a ense\u00f1ar conceptos b\u00e1sicos de programaci\u00f3n para ni\u00f1os dentro de un entorno gr\u00e1fico. Est\u00e1 basado en el lenguaje de programaci\u00f3n Logo. Una caracter\u00edstica m\u00e1s explotada de Logo es poder producir \u00abgr\u00e1ficos tortuga\u00bb (gr\u00e1ficos vectoriales), es decir, poder dar instrucciones a una tortuga virtual, un cursor gr\u00e1fico usado para crear dibujos, que en algunas versiones es un tri\u00e1ngulo, en otras tiene la figura de una tortuga vista desde arriba. Esta Tortuga amistosa introducir\u00e1 a los ni\u00f1os paso a paso en los conceptos b\u00e1sicos de programaci\u00f3n en un entorno gr\u00e1fico lleno de color. Los \u00a0con los conceptos de bucles, procedimientos, variables e instrucciones condicionales.<\/p>\n<p class=\"rtejustify\" dir=\"ltr\"><strong>&#8211; Lightbot: Code Hour<\/strong><\/p>\n<p class=\"rtejustify\" dir=\"ltr\">Su objetivo es introducir la l\u00f3gica de la programaci\u00f3n a los m\u00e1s peque\u00f1os a trav\u00e9s de un juego. El juego tiene como protagonista un peque\u00f1o robot que tiene la misi\u00f3n de iluminar la habitaci\u00f3n en la que se encuentra en cada pantalla. Para conseguirlo, los peque\u00f1os tienen que darle al robot instrucciones l\u00f3gicas para que se mueva a trav\u00e9s de un camino de baldosas hasta llegar a un \u00a0enchufe. Cada nueva habitaci\u00f3n es un nivel y existe versi\u00f3n gratuita con 20 niveles diferentes o la opci\u00f3n de pago con 50 niveles.<\/p>\n<p class=\"rtejustify\" dir=\"ltr\">Funciona tanto para Android como para iPhone.<\/p>\n<p class=\"rtejustify\" dir=\"ltr\"><strong>&#8211; Pocket Code<\/strong><\/p>\n<p class=\"rtejustify\" dir=\"ltr\">Es una app que ense\u00f1a a los peque\u00f1os lenguaje de iniciaci\u00f3n a la programaci\u00f3n en formato bloques. Es algo m\u00e1s compleja que las mencionadas anteriormente y por ella est\u00e1 orientado a un p\u00fablico infantil de entre 7 y 10 a\u00f1os.<\/p>\n<p class=\"rtejustify\" dir=\"ltr\">Con ella los peque\u00f1os podr\u00e1n desarrollar juegos y animaciones utilizando los recursos gr\u00e1ficos y musicales de la app, bloques de comandos y a la vez desarrollar su imaginaci\u00f3n y creatividad ya que podr\u00e1n modificar a su gusto juegos ya creados. Todos los juegos y animaciones creados o modificados pueden compartirse a trav\u00e9s de la app.<\/p>\n<p class=\"rtejustify\" dir=\"ltr\">Funciona solamente para Android.<\/p>\n<p class=\"rtejustify\"><strong>&#8211; Code Avengers Javascript Intro<\/strong><\/p>\n<p class=\"rtejustify\" dir=\"ltr\">Y pasando a un grupo de edad m\u00e1s enfocado en la pre y adolescencia esta app deja atr\u00e1s cualquier referencia a la programaci\u00f3n visual en bloques y les introduce de lleno en un tutorial introductorio e interactivo de Javascript.\u00a0La interfaz de la app es tambi\u00e9n bastante sencilla y con unas instrucciones claras que permiten que el usuario vaya desde ni\u00f1os y adolescentes a adultos principiantes que quieran introducirse en el mundo de la programaci\u00f3n de forma f\u00e1cil y sencilla.\u00a0Los temas est\u00e1n divididos en unidades con ejercicios, pruebas para cada lecci\u00f3n y tests finales.\u00a0La app les permitir\u00e1 aprender los conceptos b\u00e1sicos de JavaScript (variables, cadenas de texto, condicionales, \u201cprompts\u201d\u2026) de forma muy interactiva y los m\u00e1s din\u00e1mica posible.<\/p>\n<p class=\"rtejustify\">\u00a0<\/p>\n<p class=\"rtejustify\"><u><strong>Talleres de coding para ni\u00f1os <\/strong><\/u><\/p>\n<p class=\"rtejustify\">Otras tendencias que han surgido para ofrecer a los alumnos un aprendizaje l\u00fadico y significativo dentro del tema de coding, son las escuelas o talleres espec\u00edficos, donde los peque\u00f1os tienen la oportunidad de asistir en su tiempo libre o durante el verano y aprender a programar divirti\u00e9ndose y en un ambiente distendido. En ISDI estamos muy concienciados con este tema y lo llevamos a cabo a trav\u00e9s de nuestra FIDI por medio de talleres de coding. Nuestros voluntarios digitales llevan a cabo actividades en nuestro centro y adem\u00e1s visitan diferentes colegios para introducir a los m\u00e1s peque\u00f1os en el maravilloso mundo de la programaci\u00f3n.<\/p>\n<p>\u00a0Si te ha gustado el post y quieres saber m\u00e1s sobre este y otros temas, echa un vistazo a nuestro<br \/>\n <strong>M\u00e1ster en Marketing Digital.<\/strong><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/section><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El coding es una de las tendencias educativas que comienza a instaurarse dentro de los centros formativos para los m\u00e1s peque\u00f1os.<\/p>\n","protected":false},"author":23,"featured_media":14379,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[38],"tags":[],"class_list":["post-14380","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-data"],"acf":{"photo_gallery":{"galeria":[[]]}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CODING EDUCATIVO - ISDI Espa\u00f1a<\/title>\n<meta name=\"description\" content=\"Descubre las apps de aprendizaje m\u00e1s populares para introducir a los m\u00e1s peque\u00f1os en el mundo del coding y dejar que se diviertan programando.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.isdi.education\/es\/blog\/el-coding-para-los-mas-pequenos\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CODING EDUCATIVO - ISDI Espa\u00f1a\" \/>\n<meta property=\"og:description\" content=\"Descubre las apps de aprendizaje m\u00e1s populares para introducir a los m\u00e1s peque\u00f1os en el mundo del coding y dejar que se diviertan programando.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.isdi.education\/es\/blog\/el-coding-para-los-mas-pequenos\" \/>\n<meta property=\"og:site_name\" content=\"ISDI Espa\u00f1a\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/isdi.education\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-03T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-22T14:46:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.isdi.education\/es\/wp-content\/uploads\/2024\/03\/682-coding_infantil.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"infofuturo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"infofuturo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.isdi.education\\\/es\\\/blog\\\/el-coding-para-los-mas-pequenos#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.isdi.education\\\/es\\\/blog\\\/el-coding-para-los-mas-pequenos\"},\"author\":{\"name\":\"infofuturo\",\"@id\":\"https:\\\/\\\/www.isdi.education\\\/es\\\/#\\\/schema\\\/person\\\/9f30c33eda685abbcfaabf1e7b9e9f76\"},\"headline\":\"CODING EDUCATIVO\",\"datePublished\":\"2017-03-03T00:00:00+00:00\",\"dateModified\":\"2024-04-22T14:46:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.isdi.education\\\/es\\\/blog\\\/el-coding-para-los-mas-pequenos\"},\"wordCount\":1567,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.isdi.education\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.isdi.education\\\/es\\\/blog\\\/el-coding-para-los-mas-pequenos#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.isdi.education\\\/es\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/682-coding_infantil.jpg\",\"articleSection\":[\"Data\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.isdi.education\\\/es\\\/blog\\\/el-coding-para-los-mas-pequenos#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.isdi.education\\\/es\\\/blog\\\/el-coding-para-los-mas-pequenos\",\"url\":\"https:\\\/\\\/www.isdi.education\\\/es\\\/blog\\\/el-coding-para-los-mas-pequenos\",\"name\":\"CODING EDUCATIVO - ISDI Espa\u00f1a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.isdi.education\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.isdi.education\\\/es\\\/blog\\\/el-coding-para-los-mas-pequenos#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.isdi.education\\\/es\\\/blog\\\/el-coding-para-los-mas-pequenos#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.isdi.education\\\/es\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/682-coding_infantil.jpg\",\"datePublished\":\"2017-03-03T00:00:00+00:00\",\"dateModified\":\"2024-04-22T14:46:22+00:00\",\"description\":\"Descubre las apps de aprendizaje m\u00e1s populares para introducir a los m\u00e1s peque\u00f1os en el mundo del coding y dejar que se diviertan programando.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.isdi.education\\\/es\\\/blog\\\/el-coding-para-los-mas-pequenos#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.isdi.education\\\/es\\\/blog\\\/el-coding-para-los-mas-pequenos\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.isdi.education\\\/es\\\/blog\\\/el-coding-para-los-mas-pequenos#primaryimage\",\"url\":\"https:\\\/\\\/www.isdi.education\\\/es\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/682-coding_infantil.jpg\",\"contentUrl\":\"https:\\\/\\\/www.isdi.education\\\/es\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/682-coding_infantil.jpg\",\"width\":600,\"height\":400,\"caption\":\"CODING EDUCATIVO\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.isdi.education\\\/es\\\/blog\\\/el-coding-para-los-mas-pequenos#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.isdi.education\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CODING EDUCATIVO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.isdi.education\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.isdi.education\\\/es\\\/\",\"name\":\"ISDI Espa\u00f1a | La Escuela de Negocios de la Era Digital\",\"description\":\"Descubre la formaci\u00f3n que te abrir\u00e1 las puertas a la era digital. Entra a formar parte de la primera escuela de negocios y direcci\u00f3n nativa digital.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.isdi.education\\\/es\\\/#organization\"},\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.isdi.education\\\/es\\\/#organization\",\"name\":\"ISDI Espa\u00f1a | La Escuela de Negocios de la Era Digital\",\"url\":\"https:\\\/\\\/www.isdi.education\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.isdi.education\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.isdi.education\\\/es\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Favicon.png\",\"contentUrl\":\"https:\\\/\\\/www.isdi.education\\\/es\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-Favicon.png\",\"width\":512,\"height\":512,\"caption\":\"ISDI Espa\u00f1a | La Escuela de Negocios de la Era Digital\"},\"image\":{\"@id\":\"https:\\\/\\\/www.isdi.education\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/isdi.education\",\"https:\\\/\\\/www.linkedin.com\\\/school\\\/isdi\\\/?originalSubdomain=es\",\"https:\\\/\\\/www.instagram.com\\\/isdi_edu\\\/?hl=es\",\"https:\\\/\\\/www.tiktok.com\\\/@isdi_edu\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/ISDItv\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.isdi.education\\\/es\\\/#\\\/schema\\\/person\\\/9f30c33eda685abbcfaabf1e7b9e9f76\",\"name\":\"infofuturo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.isdi.education\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/1\\\/06e1ec358746bcb8bb25471d95ddc6aa.jpg?ver=1788340701\",\"url\":\"https:\\\/\\\/www.isdi.education\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/1\\\/06e1ec358746bcb8bb25471d95ddc6aa.jpg?ver=1788340701\",\"contentUrl\":\"https:\\\/\\\/www.isdi.education\\\/es\\\/wp-content\\\/litespeed\\\/avatar\\\/1\\\/06e1ec358746bcb8bb25471d95ddc6aa.jpg?ver=1788340701\",\"caption\":\"infofuturo\"},\"url\":\"https:\\\/\\\/www.isdi.education\\\/es\\\/author\\\/infofuturo\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CODING EDUCATIVO - ISDI Espa\u00f1a","description":"Descubre las apps de aprendizaje m\u00e1s populares para introducir a los m\u00e1s peque\u00f1os en el mundo del coding y dejar que se diviertan programando.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.isdi.education\/es\/blog\/el-coding-para-los-mas-pequenos","og_locale":"es_ES","og_type":"article","og_title":"CODING EDUCATIVO - ISDI Espa\u00f1a","og_description":"Descubre las apps de aprendizaje m\u00e1s populares para introducir a los m\u00e1s peque\u00f1os en el mundo del coding y dejar que se diviertan programando.","og_url":"https:\/\/www.isdi.education\/es\/blog\/el-coding-para-los-mas-pequenos","og_site_name":"ISDI Espa\u00f1a","article_publisher":"https:\/\/www.facebook.com\/isdi.education","article_published_time":"2017-03-03T00:00:00+00:00","article_modified_time":"2024-04-22T14:46:22+00:00","og_image":[{"width":600,"height":400,"url":"https:\/\/www.isdi.education\/es\/wp-content\/uploads\/2024\/03\/682-coding_infantil.jpg","type":"image\/jpeg"}],"author":"infofuturo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"infofuturo","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.isdi.education\/es\/blog\/el-coding-para-los-mas-pequenos#article","isPartOf":{"@id":"https:\/\/www.isdi.education\/es\/blog\/el-coding-para-los-mas-pequenos"},"author":{"name":"infofuturo","@id":"https:\/\/www.isdi.education\/es\/#\/schema\/person\/9f30c33eda685abbcfaabf1e7b9e9f76"},"headline":"CODING EDUCATIVO","datePublished":"2017-03-03T00:00:00+00:00","dateModified":"2024-04-22T14:46:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.isdi.education\/es\/blog\/el-coding-para-los-mas-pequenos"},"wordCount":1567,"commentCount":0,"publisher":{"@id":"https:\/\/www.isdi.education\/es\/#organization"},"image":{"@id":"https:\/\/www.isdi.education\/es\/blog\/el-coding-para-los-mas-pequenos#primaryimage"},"thumbnailUrl":"https:\/\/www.isdi.education\/es\/wp-content\/uploads\/2024\/03\/682-coding_infantil.jpg","articleSection":["Data"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.isdi.education\/es\/blog\/el-coding-para-los-mas-pequenos#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.isdi.education\/es\/blog\/el-coding-para-los-mas-pequenos","url":"https:\/\/www.isdi.education\/es\/blog\/el-coding-para-los-mas-pequenos","name":"CODING EDUCATIVO - ISDI Espa\u00f1a","isPartOf":{"@id":"https:\/\/www.isdi.education\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.isdi.education\/es\/blog\/el-coding-para-los-mas-pequenos#primaryimage"},"image":{"@id":"https:\/\/www.isdi.education\/es\/blog\/el-coding-para-los-mas-pequenos#primaryimage"},"thumbnailUrl":"https:\/\/www.isdi.education\/es\/wp-content\/uploads\/2024\/03\/682-coding_infantil.jpg","datePublished":"2017-03-03T00:00:00+00:00","dateModified":"2024-04-22T14:46:22+00:00","description":"Descubre las apps de aprendizaje m\u00e1s populares para introducir a los m\u00e1s peque\u00f1os en el mundo del coding y dejar que se diviertan programando.","breadcrumb":{"@id":"https:\/\/www.isdi.education\/es\/blog\/el-coding-para-los-mas-pequenos#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.isdi.education\/es\/blog\/el-coding-para-los-mas-pequenos"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.isdi.education\/es\/blog\/el-coding-para-los-mas-pequenos#primaryimage","url":"https:\/\/www.isdi.education\/es\/wp-content\/uploads\/2024\/03\/682-coding_infantil.jpg","contentUrl":"https:\/\/www.isdi.education\/es\/wp-content\/uploads\/2024\/03\/682-coding_infantil.jpg","width":600,"height":400,"caption":"CODING EDUCATIVO"},{"@type":"BreadcrumbList","@id":"https:\/\/www.isdi.education\/es\/blog\/el-coding-para-los-mas-pequenos#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.isdi.education\/es\/"},{"@type":"ListItem","position":2,"name":"CODING EDUCATIVO"}]},{"@type":"WebSite","@id":"https:\/\/www.isdi.education\/es\/#website","url":"https:\/\/www.isdi.education\/es\/","name":"ISDI Espa\u00f1a | La Escuela de Negocios de la Era Digital","description":"Descubre la formaci\u00f3n que te abrir\u00e1 las puertas a la era digital. Entra a formar parte de la primera escuela de negocios y direcci\u00f3n nativa digital.","publisher":{"@id":"https:\/\/www.isdi.education\/es\/#organization"},"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.isdi.education\/es\/#organization","name":"ISDI Espa\u00f1a | La Escuela de Negocios de la Era Digital","url":"https:\/\/www.isdi.education\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.isdi.education\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.isdi.education\/es\/wp-content\/uploads\/2024\/02\/cropped-Favicon.png","contentUrl":"https:\/\/www.isdi.education\/es\/wp-content\/uploads\/2024\/02\/cropped-Favicon.png","width":512,"height":512,"caption":"ISDI Espa\u00f1a | La Escuela de Negocios de la Era Digital"},"image":{"@id":"https:\/\/www.isdi.education\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/isdi.education","https:\/\/www.linkedin.com\/school\/isdi\/?originalSubdomain=es","https:\/\/www.instagram.com\/isdi_edu\/?hl=es","https:\/\/www.tiktok.com\/@isdi_edu","https:\/\/www.youtube.com\/user\/ISDItv"]},{"@type":"Person","@id":"https:\/\/www.isdi.education\/es\/#\/schema\/person\/9f30c33eda685abbcfaabf1e7b9e9f76","name":"infofuturo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.isdi.education\/es\/wp-content\/litespeed\/avatar\/1\/06e1ec358746bcb8bb25471d95ddc6aa.jpg?ver=1788340701","url":"https:\/\/www.isdi.education\/es\/wp-content\/litespeed\/avatar\/1\/06e1ec358746bcb8bb25471d95ddc6aa.jpg?ver=1788340701","contentUrl":"https:\/\/www.isdi.education\/es\/wp-content\/litespeed\/avatar\/1\/06e1ec358746bcb8bb25471d95ddc6aa.jpg?ver=1788340701","caption":"infofuturo"},"url":"https:\/\/www.isdi.education\/es\/author\/infofuturo"}]}},"_links":{"self":[{"href":"https:\/\/www.isdi.education\/es\/wp-json\/wp\/v2\/posts\/14380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.isdi.education\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.isdi.education\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.isdi.education\/es\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/www.isdi.education\/es\/wp-json\/wp\/v2\/comments?post=14380"}],"version-history":[{"count":0,"href":"https:\/\/www.isdi.education\/es\/wp-json\/wp\/v2\/posts\/14380\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.isdi.education\/es\/wp-json\/wp\/v2\/media\/14379"}],"wp:attachment":[{"href":"https:\/\/www.isdi.education\/es\/wp-json\/wp\/v2\/media?parent=14380"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.isdi.education\/es\/wp-json\/wp\/v2\/categories?post=14380"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.isdi.education\/es\/wp-json\/wp\/v2\/tags?post=14380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}